{"id":2197,"date":"2023-01-23T16:26:17","date_gmt":"2023-01-23T15:26:17","guid":{"rendered":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/"},"modified":"2023-06-17T18:19:37","modified_gmt":"2023-06-17T16:19:37","slug":"traufgang-schlossfelsenpfad","status":"publish","type":"tribe_events","link":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/","title":{"rendered":"Traufgang Schlossfelsenpfad"},"content":{"rendered":"<p>Wundersch\u00f6ne Panoramablicke bis zu den Alpen, Wege durch malerische Buchenw\u00e4lder. Traumhaft gelegene, offene Wacholderheidelandschaft mit Silberdisteln und majest\u00e4tischen, uralten Traufbuchen rund um Siechenb\u00fchl und der Anh\u00f6he \u201eSt\u00e4hlernes M\u00e4nnlein\u201c. Herrliche Ausblicke \u00fcber die T\u00e4ler und H\u00f6hen von Albstadt. Gutes Festes Schuhwerk ist empfehlenswert, Trittsicherheit unabdingbar.<\/p>\n<table>\n<tbody>\n<tr>\n<td class=\"tdh_wp\">Wanderf\u00fchrung:<\/td>\n<td class=\"tdh_wp\">Siegfried K\u00f6nig<\/td>\n<\/tr>\n<tr>\n<td class=\"td_wp\">Gehzeit:<\/td>\n<td class=\"td_wp\">ca. 5,5 Std.<br \/>\n15 km, 481 hm<\/td>\n<\/tr>\n<tr>\n<td class=\"td_wp\">Kategorie 3<\/td>\n<td class=\"td_wp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/blaueRaute.png\" alt=\"\" width=\"30\" height=\"16\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"td_wp\">Treffpunkt:<\/td>\n<td class=\"td_wp\">09:00 Uhr, Parkplatz Klosterweiher<\/td>\n<\/tr>\n<tr>\n<td class=\"td_wp\">Anmeldung:<\/td>\n<td class=\"td_wp\">07724 \/ 2802<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><small>Bildquelle: <a>CC BY-ND<\/a>, Albstadt Tourismus<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wundersch\u00f6ne Panoramablicke bis zu den Alpen, Wege durch malerische Buchenw\u00e4lder. Traumhaft gelegene, offene Wacholderheidelandschaft mit Silberdisteln und majest\u00e4tischen, uralten Traufbuchen rund um Siechenb\u00fchl und der Anh\u00f6he \u201eSt\u00e4hlernes M\u00e4nnlein\u201c. Herrliche Ausblicke \u00fcber die T\u00e4ler und H\u00f6hen von Albstadt. Gutes Festes Schuhwerk ist empfehlenswert, Trittsicherheit unabdingbar. Wanderf\u00fchrung: Siegfried K\u00f6nig Gehzeit: ca. 5,5 Std. 15 km, 481 hm &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":2146,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[2,7],"class_list":["post-2197","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-jahresprogramm","tribe_events_cat-wanderung","cat_jahresprogramm","cat_wanderung","nodate","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traufgang Schlossfelsenpfad - Schwarzwaldverein St. Georgen e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traufgang Schlossfelsenpfad - Schwarzwaldverein St. Georgen e.V.\" \/>\n<meta property=\"og:description\" content=\"Wundersch\u00f6ne Panoramablicke bis zu den Alpen, Wege durch malerische Buchenw\u00e4lder. Traumhaft gelegene, offene Wacholderheidelandschaft mit Silberdisteln und majest\u00e4tischen, uralten Traufbuchen rund um Siechenb\u00fchl und der Anh\u00f6he \u201eSt\u00e4hlernes M\u00e4nnlein\u201c. Herrliche Ausblicke \u00fcber die T\u00e4ler und H\u00f6hen von Albstadt. Gutes Festes Schuhwerk ist empfehlenswert, Trittsicherheit unabdingbar. Wanderf\u00fchrung: Siegfried K\u00f6nig Gehzeit: ca. 5,5 Std. 15 km, 481 hm &hellip; Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/\" \/>\n<meta property=\"og:site_name\" content=\"Schwarzwaldverein St. Georgen e.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-17T16:19:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/2023\/Schlossfelsturm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/traufgang-schlossfelsenpfad\\\/\",\"url\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/traufgang-schlossfelsenpfad\\\/\",\"name\":\"Traufgang Schlossfelsenpfad - Schwarzwaldverein St. Georgen e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/traufgang-schlossfelsenpfad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/traufgang-schlossfelsenpfad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/wp-content\\\/uploads\\\/2023\\\/Schlossfelsturm.jpg\",\"datePublished\":\"2023-01-23T15:26:17+00:00\",\"dateModified\":\"2023-06-17T16:19:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/traufgang-schlossfelsenpfad\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/traufgang-schlossfelsenpfad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/traufgang-schlossfelsenpfad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/wp-content\\\/uploads\\\/2023\\\/Schlossfelsturm.jpg\",\"contentUrl\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/wp-content\\\/uploads\\\/2023\\\/Schlossfelsturm.jpg\",\"width\":1200,\"height\":801},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/traufgang-schlossfelsenpfad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Traufgang Schlossfelsenpfad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/#website\",\"url\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/\",\"name\":\"Schwarzwaldverein St. Georgen e.V.\",\"description\":\"Wandern, Wege, Naturschutz, Familien, Wanderheim Lindenb\u00fcble\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traufgang Schlossfelsenpfad - Schwarzwaldverein St. Georgen e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/","og_locale":"de_DE","og_type":"article","og_title":"Traufgang Schlossfelsenpfad - Schwarzwaldverein St. Georgen e.V.","og_description":"Wundersch\u00f6ne Panoramablicke bis zu den Alpen, Wege durch malerische Buchenw\u00e4lder. Traumhaft gelegene, offene Wacholderheidelandschaft mit Silberdisteln und majest\u00e4tischen, uralten Traufbuchen rund um Siechenb\u00fchl und der Anh\u00f6he \u201eSt\u00e4hlernes M\u00e4nnlein\u201c. Herrliche Ausblicke \u00fcber die T\u00e4ler und H\u00f6hen von Albstadt. Gutes Festes Schuhwerk ist empfehlenswert, Trittsicherheit unabdingbar. Wanderf\u00fchrung: Siegfried K\u00f6nig Gehzeit: ca. 5,5 Std. 15 km, 481 hm &hellip; Weiterlesen","og_url":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/","og_site_name":"Schwarzwaldverein St. Georgen e.V.","article_modified_time":"2023-06-17T16:19:37+00:00","og_image":[{"width":1200,"height":801,"url":"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/2023\/Schlossfelsturm.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/","url":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/","name":"Traufgang Schlossfelsenpfad - Schwarzwaldverein St. Georgen e.V.","isPartOf":{"@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/#primaryimage"},"image":{"@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/2023\/Schlossfelsturm.jpg","datePublished":"2023-01-23T15:26:17+00:00","dateModified":"2023-06-17T16:19:37+00:00","breadcrumb":{"@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/#primaryimage","url":"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/2023\/Schlossfelsturm.jpg","contentUrl":"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/2023\/Schlossfelsturm.jpg","width":1200,"height":801},{"@type":"BreadcrumbList","@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/traufgang-schlossfelsenpfad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.schwarzwaldverein-st-georgen.de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/events\/"},{"@type":"ListItem","position":3,"name":"Traufgang Schlossfelsenpfad"}]},{"@type":"WebSite","@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/#website","url":"https:\/\/www.schwarzwaldverein-st-georgen.de\/","name":"Schwarzwaldverein St. Georgen e.V.","description":"Wandern, Wege, Naturschutz, Familien, Wanderheim Lindenb\u00fcble","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schwarzwaldverein-st-georgen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/2197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/comments?post=2197"}],"version-history":[{"count":2,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/2197\/revisions"}],"predecessor-version":[{"id":2284,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/2197\/revisions\/2284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/media\/2146"}],"wp:attachment":[{"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/media?parent=2197"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tags?post=2197"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=2197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}