{"id":2192,"date":"2023-01-23T16:26:01","date_gmt":"2023-01-23T15:26:01","guid":{"rendered":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/"},"modified":"2023-01-27T09:38:15","modified_gmt":"2023-01-27T08:38:15","slug":"rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos","status":"publish","type":"tribe_events","link":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/","title":{"rendered":"Rote &#8211; Raute &#8211; Treff: Vogelkundliche F\u00fchrung im Schwenninger Moos"},"content":{"rendered":"<p>Ernst Beiter, Mitarbeiter beim Umweltschutzzentrum in Schwenningen, f\u00fchrt uns durch das Naturschutzgebiet Schwenninger Moos und zeigt uns die Vielfalt der dort lebenden V\u00f6gel. Weil das vielstimmige Vogelkonzert schon am fr\u00fchen Vormittag verklingt, lohnt sich das fr\u00fche Aufstehen. Die Teilnehmerzahl ist begrenzt. Bitte rechtzeitig anmelden!<br \/>\nKosten: 5\u20ac pro Person f\u00fcr die F\u00fchrung<\/p>\n<table>\n<tbody>\n<tr>\n<td class=\"tdh_wp\">Wanderf\u00fchrung:<\/td>\n<td class=\"tdh_wp\">Doris Krause<\/td>\n<\/tr>\n<tr>\n<td class=\"td_wp\">Gehzeit:<\/td>\n<td class=\"td_wp\">\nca. 5 km<\/td>\n<\/tr>\n<tr>\n<td class=\"td_wp\">Kategorie 2<\/td>\n<td class=\"td_wp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/gelbeRaute.png\" alt=\"\" width=\"30\" height=\"16\" \/><\/td>\n<\/tr>\n<tr>\n<td class=\"td_wp\">Treffpunkt:<\/td>\n<td class=\"td_wp\">06:30 Uhr, Parkplatz Klosterweiher<\/td>\n<\/tr>\n<tr>\n<td class=\"td_wp\">Anmeldung:<\/td>\n<td class=\"td_wp\">07724 \/ 4798<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><small>Bildquelle: Doris Krause, <a>CC BY-ND<\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ernst Beiter, Mitarbeiter beim Umweltschutzzentrum in Schwenningen, f\u00fchrt uns durch das Naturschutzgebiet Schwenninger Moos und zeigt uns die Vielfalt der dort lebenden V\u00f6gel. Weil das vielstimmige Vogelkonzert schon am fr\u00fchen Vormittag verklingt, lohnt sich das fr\u00fche Aufstehen. Die Teilnehmerzahl ist begrenzt. Bitte rechtzeitig anmelden! Kosten: 5\u20ac pro Person f\u00fcr die F\u00fchrung Wanderf\u00fchrung: Doris Krause Gehzeit: &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":2147,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[2,3],"class_list":["post-2192","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-jahresprogramm","tribe_events_cat-rote-raute-treff","cat_jahresprogramm","cat_rote-raute-treff","nodate","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rote - Raute - Treff: Vogelkundliche F\u00fchrung im Schwenninger Moos - Schwarzwaldverein St. Georgen e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rote - Raute - Treff: Vogelkundliche F\u00fchrung im Schwenninger Moos - Schwarzwaldverein St. Georgen e.V.\" \/>\n<meta property=\"og:description\" content=\"Ernst Beiter, Mitarbeiter beim Umweltschutzzentrum in Schwenningen, f\u00fchrt uns durch das Naturschutzgebiet Schwenninger Moos und zeigt uns die Vielfalt der dort lebenden V\u00f6gel. Weil das vielstimmige Vogelkonzert schon am fr\u00fchen Vormittag verklingt, lohnt sich das fr\u00fche Aufstehen. Die Teilnehmerzahl ist begrenzt. Bitte rechtzeitig anmelden! Kosten: 5\u20ac pro Person f\u00fcr die F\u00fchrung Wanderf\u00fchrung: Doris Krause Gehzeit: &hellip; Weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/\" \/>\n<meta property=\"og:site_name\" content=\"Schwarzwaldverein St. Georgen e.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-27T08:38:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/2023\/IMG_6268.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1008\" \/>\n\t<meta property=\"og:image:height\" content=\"756\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\\\/\",\"url\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\\\/\",\"name\":\"Rote - Raute - Treff: Vogelkundliche F\u00fchrung im Schwenninger Moos - Schwarzwaldverein St. Georgen e.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/wp-content\\\/uploads\\\/2023\\\/IMG_6268.jpg\",\"datePublished\":\"2023-01-23T15:26:01+00:00\",\"dateModified\":\"2023-01-27T08:38:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/wp-content\\\/uploads\\\/2023\\\/IMG_6268.jpg\",\"contentUrl\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/wp-content\\\/uploads\\\/2023\\\/IMG_6268.jpg\",\"width\":1008,\"height\":756},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/event\\\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/index.php\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rote &#8211; Raute &#8211; Treff: Vogelkundliche F\u00fchrung im Schwenninger Moos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/#website\",\"url\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/\",\"name\":\"Schwarzwaldverein St. Georgen e.V.\",\"description\":\"Wandern, Wege, Naturschutz, Familien, Wanderheim Lindenb\u00fcble\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.schwarzwaldverein-st-georgen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rote - Raute - Treff: Vogelkundliche F\u00fchrung im Schwenninger Moos - Schwarzwaldverein St. Georgen e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/","og_locale":"de_DE","og_type":"article","og_title":"Rote - Raute - Treff: Vogelkundliche F\u00fchrung im Schwenninger Moos - Schwarzwaldverein St. Georgen e.V.","og_description":"Ernst Beiter, Mitarbeiter beim Umweltschutzzentrum in Schwenningen, f\u00fchrt uns durch das Naturschutzgebiet Schwenninger Moos und zeigt uns die Vielfalt der dort lebenden V\u00f6gel. Weil das vielstimmige Vogelkonzert schon am fr\u00fchen Vormittag verklingt, lohnt sich das fr\u00fche Aufstehen. Die Teilnehmerzahl ist begrenzt. Bitte rechtzeitig anmelden! Kosten: 5\u20ac pro Person f\u00fcr die F\u00fchrung Wanderf\u00fchrung: Doris Krause Gehzeit: &hellip; Weiterlesen","og_url":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/","og_site_name":"Schwarzwaldverein St. Georgen e.V.","article_modified_time":"2023-01-27T08:38:15+00:00","og_image":[{"width":1008,"height":756,"url":"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/2023\/IMG_6268.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/","url":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/","name":"Rote - Raute - Treff: Vogelkundliche F\u00fchrung im Schwenninger Moos - Schwarzwaldverein St. Georgen e.V.","isPartOf":{"@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/#primaryimage"},"image":{"@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/2023\/IMG_6268.jpg","datePublished":"2023-01-23T15:26:01+00:00","dateModified":"2023-01-27T08:38:15+00:00","breadcrumb":{"@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/#primaryimage","url":"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/2023\/IMG_6268.jpg","contentUrl":"https:\/\/www.schwarzwaldverein-st-georgen.de\/wp-content\/uploads\/2023\/IMG_6268.jpg","width":1008,"height":756},{"@type":"BreadcrumbList","@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/event\/rote-raute-treff-vogelkundliche-fuehrung-im-schwenninger-moos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.schwarzwaldverein-st-georgen.de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/events\/"},{"@type":"ListItem","position":3,"name":"Rote &#8211; Raute &#8211; Treff: Vogelkundliche F\u00fchrung im Schwenninger Moos"}]},{"@type":"WebSite","@id":"https:\/\/www.schwarzwaldverein-st-georgen.de\/#website","url":"https:\/\/www.schwarzwaldverein-st-georgen.de\/","name":"Schwarzwaldverein St. Georgen e.V.","description":"Wandern, Wege, Naturschutz, Familien, Wanderheim Lindenb\u00fcble","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schwarzwaldverein-st-georgen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/2192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/comments?post=2192"}],"version-history":[{"count":1,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/2192\/revisions"}],"predecessor-version":[{"id":2224,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/2192\/revisions\/2224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/media\/2147"}],"wp:attachment":[{"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/media?parent=2192"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tags?post=2192"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.schwarzwaldverein-st-georgen.de\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=2192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}